{"id":5383,"date":"2024-04-08T10:14:49","date_gmt":"2024-04-08T14:14:49","guid":{"rendered":"https:\/\/fundadeporte.gob.ve\/carabobo\/?p=5383"},"modified":"2024-04-08T11:13:55","modified_gmt":"2024-04-08T15:13:55","slug":"heriberto-prieto-grand-prix-de-xalapa-2024","status":"publish","type":"post","link":"https:\/\/fundadeporte.gob.ve\/carabobo\/heriberto-prieto-grand-prix-de-xalapa-2024\/","title":{"rendered":"El carabobe\u00f1o Heriberto Prieto conquista Plata en el Grand Prix de Xalapa 2024"},"content":{"rendered":"<h4><span style=\"color: #000080;\">El Para Atleta Heriberto Prieto (clase F40) de la disciplina de Para Atletismo concurs\u00f3 en la prueba de impulso de Bala y conquistando una medalla de Plata junto a su entrenadora Adriana Benaventa, quienes dijeron presente en la competencia realizada en tierras mexicanas que reuni\u00f3 a 496 para atletas de 21 naciones.<\/span><\/h4>\n<p>El deportista regional obtuvo medalla de Plata en los pasados Juegos Parapanamericanos de Santiago 2023 e igualmente conquist\u00f3 Plata en los V Juegos Parapanamericanos Juveniles Bogot\u00e1 2023.<\/p>\n<figure id=\"attachment_5387\" aria-describedby=\"caption-attachment-5387\" style=\"width: 753px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5387\" src=\"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2024\/04\/El-Para-Atleta-Heriberto-Prieto-de-la-disciplina-de-Para-Atletismo-.jpg\" alt=\"Heriberto Prieto (clase F40) de la disciplina de Para Atletismo concurs\u00f3 en la prueba de impulso de Bala y conquistando una medalla de Plata junto a su entrenadora Adriana Benaventa\" width=\"753\" height=\"461\" srcset=\"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2024\/04\/El-Para-Atleta-Heriberto-Prieto-de-la-disciplina-de-Para-Atletismo-.jpg 753w, https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2024\/04\/El-Para-Atleta-Heriberto-Prieto-de-la-disciplina-de-Para-Atletismo--300x184.jpg 300w\" sizes=\"auto, (max-width: 753px) 100vw, 753px\" \/><figcaption id=\"caption-attachment-5387\" class=\"wp-caption-text\">Heriberto Prieto y su entrenadora Adriana Benaventa<\/figcaption><\/figure>\n<p><span style=\"color: #000000;\">El equipo venezolano de Paratletismo estuvo conformado por m\u00e1s de 10 atletas quienes compitieron en el Grand Prix de Para Atletismo que se llev\u00f3 a cabo en el Estadio \u201cHeriberto Jara Corona\u201d de la ciudad de Xalapa en M\u00e9xico desde el viernes 5 hasta el domingo 7 de abril. En este encuentro deportivo los para atletas lograron sus mejores tiempos y marcas, en la que fue la \u00faltima oportunidad de clasificar al Campeonato Mundial Kobe 2024, que se llevar\u00e1 a cabo del 17 al 25 de mayo y que otorgar\u00e1 plazas a los Juegos Paral\u00edmpicos Par\u00eds 2024.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5386\" src=\"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2024\/04\/Venezuela-para-atletas-rumbo-al-Grand-Prix-de-Xalapa-2024.jpg\" alt=\"para atletismo venezuela\" width=\"568\" height=\"299\" srcset=\"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2024\/04\/Venezuela-para-atletas-rumbo-al-Grand-Prix-de-Xalapa-2024.jpg 568w, https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2024\/04\/Venezuela-para-atletas-rumbo-al-Grand-Prix-de-Xalapa-2024-300x158.jpg 300w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/p>\n<p>Adem\u00e1s de nuestro atleta regional Heriberto Prieto los representantes de Venezuela en esta competencia son: Jos\u00e9 P\u00e9rez F55, Rafael Bracho T11\/F11, Alfredo Mora F41, Armando Marcano T11\/F11, Daniel Morales T47, Josandre Verd\u00fa T37\/F37, Anabel Polanco T35, Jes\u00fas Medina F40, Roger Chirinos T44\/F44y Jes\u00fas Far\u00edas T11\/F11.<\/p>\n<p>Entre los pa\u00edses asistentes al certamen, no s\u00f3lo acudieron los de la regi\u00f3n de Am\u00e9rica, como Venezuela, Estados Unidos, Argentina, Cuba y Colombia, entre otros, sino tambi\u00e9n hay presencia de pa\u00edses europeos como Espa\u00f1a y Alemania, adem\u00e1s de africanos como es el caso de Ghana.<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"iYktsg9Nhi\"><p><a href=\"https:\/\/fundadeporte.gob.ve\/carabobo\/heriberto-prieto-juegos-parapanamericanos-de-santiago-2023\/\">Heriberto Prieto gana Plata en los Juegos Parapanamericanos de Santiago 2023<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abHeriberto Prieto gana Plata en los Juegos Parapanamericanos de Santiago 2023\u00bb \u2014 Fundadeporte\" src=\"https:\/\/fundadeporte.gob.ve\/carabobo\/heriberto-prieto-juegos-parapanamericanos-de-santiago-2023\/embed\/#?secret=io0bBFonVf#?secret=iYktsg9Nhi\" data-secret=\"iYktsg9Nhi\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Para Atleta Heriberto Prieto (clase F40) de la disciplina de Para Atletismo concurs\u00f3 en la prueba de impulso de Bala y conquistando una medalla de Plata junto a su entrenadora Adriana Benaventa, quienes dijeron presente en la competencia realizada en tierras mexicanas que reuni\u00f3 a 496 para atletas de 21 naciones. El deportista regional [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":5434,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[28],"tags":[240],"class_list":["post-5383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atletismo","tag-heriberto-prieto"],"_links":{"self":[{"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/posts\/5383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/comments?post=5383"}],"version-history":[{"count":10,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/posts\/5383\/revisions"}],"predecessor-version":[{"id":5435,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/posts\/5383\/revisions\/5435"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/media\/5434"}],"wp:attachment":[{"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/media?parent=5383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/categories?post=5383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/tags?post=5383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}