{"id":3695,"date":"2023-05-27T10:21:35","date_gmt":"2023-05-27T14:21:35","guid":{"rendered":"https:\/\/fundadeporte.gob.ve\/carabobo\/?p=3695"},"modified":"2023-05-27T10:22:29","modified_gmt":"2023-05-27T14:22:29","slug":"1era-valida-nacional-de-skate","status":"publish","type":"post","link":"https:\/\/fundadeporte.gob.ve\/carabobo\/1era-valida-nacional-de-skate\/","title":{"rendered":"Puerto Cabello se prepara para la 1era V\u00e1lida Nacional de Skate"},"content":{"rendered":"<h4><span style=\"color: #035e66;\">M\u00e1s de 250 atletas a nivel nacional estar\u00e1n representando a sus estados en la primera edici\u00f3n de esta competencia modalidad Bowl, en la \u00abCopa HM LLantas Valencia Bowl Clash Puerto Cabilla\u00bb que se realizar\u00e1 el s\u00e1bado 17 de junio a partir de las 10 am.<\/span><\/h4>\n<p>El Skatepark de Puerto Cabello ser\u00e1 el escenario donde se definir\u00e1 el ranking nacional y los cupos a los eventos internacionales a cumplir por la Comisi\u00f3n T\u00e9cnica Nacional de Skateboarding Venezolano CTNS. Esta estructura deportiva cumple con los requerimientos para cubrir un evento de esta categor\u00eda, conformado por un circuito que permite el control y la fluidez necesarios para la actividad extrema, albergando eventos como el 1er Invitacional de Skate, el Open Bowl Jam Puerto Cabilla, el Bowl Clash Puerto Cabilla, el Skate Day, el 2do Campeonato Nacional de Roller Free Style entre otros.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3698\" src=\"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2023\/05\/1era-Valida-Nacional-de-Skate-2.jpg\" alt=\"1era V\u00e1lida Nacional de Skate\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2023\/05\/1era-Valida-Nacional-de-Skate-2.jpg 1080w, https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2023\/05\/1era-Valida-Nacional-de-Skate-2-300x300.jpg 300w, https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2023\/05\/1era-Valida-Nacional-de-Skate-2-1024x1024.jpg 1024w, https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2023\/05\/1era-Valida-Nacional-de-Skate-2-150x150.jpg 150w, https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2023\/05\/1era-Valida-Nacional-de-Skate-2-768x768.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p>Las Categor\u00edas que se estar\u00e1n definiendo en este campeonato son : Pre-infantil Mixto, Infantil Mixto, Juvenil Masculino, Juvenil Femenino, Open Masculino y Open Femenino. Las inscripciones para este evento permanecer\u00e1n abiertas hasta el 12 de junio.<\/p>\n<p>El evento cuenta con el apoyo de la Gobernaci\u00f3n de Carabobo y el Gobernador Rafael Lacava, Fundadeporte con Presidente Jhonny Del Corral, adem\u00e1s de otras instituciones como Indepuertos, Alcald\u00eda de Puerto Cabello, Fevepatinaje, el Comit\u00e9 Ol\u00edmpico Venezolano y otros patrocinantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 250 atletas a nivel nacional estar\u00e1n representando a sus estados en la primera edici\u00f3n de esta competencia modalidad Bowl, en la \u00abCopa HM LLantas Valencia Bowl Clash Puerto Cabilla\u00bb que se realizar\u00e1 el s\u00e1bado 17 de junio a partir de las 10 am. El Skatepark de Puerto Cabello ser\u00e1 el escenario donde se [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3697,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[66],"tags":[236],"class_list":["post-3695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-valida-nacional-de-skate"],"_links":{"self":[{"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/posts\/3695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/comments?post=3695"}],"version-history":[{"count":3,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/posts\/3695\/revisions"}],"predecessor-version":[{"id":3700,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/posts\/3695\/revisions\/3700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/media\/3697"}],"wp:attachment":[{"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/media?parent=3695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/categories?post=3695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/tags?post=3695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}