{"id":3488,"date":"2023-04-25T09:53:28","date_gmt":"2023-04-25T13:53:28","guid":{"rendered":"https:\/\/fundadeporte.gob.ve\/carabobo\/?p=3488"},"modified":"2023-04-25T10:19:08","modified_gmt":"2023-04-25T14:19:08","slug":"futbol-sala-femenino-juegos-alba-2023","status":"publish","type":"post","link":"https:\/\/fundadeporte.gob.ve\/carabobo\/futbol-sala-femenino-juegos-alba-2023\/","title":{"rendered":"Venezuela se titula campeona en el F\u00fatbol Sala femenino de los Juegos Alba 2023"},"content":{"rendered":"<h4><span style=\"color: #003366;\">El equipo de Venezuela B obtiene el oro luego de vencer 3 goles por 2 al equipo nacional A en la quinta edici\u00f3n de los juegos deportivos que re\u00fane a los pa\u00edses del Alba e invitados especiales.<\/span><\/h4>\n<p>El combinado Sub20, qui\u00e9nes jugaron de color blanco, madrugaron en el marcador a sus similares con gol de la capitana Ana Quintero en el primer tiempo (11:32).<\/p>\n<p>Iniciando el segundo periodo las de vinotinto empataron las acciones 1-1 con gol de la carabobe\u00f1a Glorimar Su\u00e1rez (04:22), acci\u00f3n que no afect\u00f3 a las jovencitas dirigidas por Helianny Revilla, sumando un tanto con anotaci\u00f3n de Alejandra Sarmiento (13:35).<\/p>\n<p>En el minuto 15:30 el conjunto A dirigido por Milagro Infante volvi\u00f3 a empatar las acciones 2-2. Ambos equipos buscaban consagrase en los \u00abJuegos de la Amistad\u00bb hasta que lleg\u00f3 el gol decisivo en los pies de Di\u00f3celis Nu\u00f1ez (19:00).<br \/>\nEl podio qued\u00f3 conformado por Venezuela Equipo B con Oro y Equipo A con Plata y Nicaragua con la medalla de Bronce.<\/p>\n<figure id=\"attachment_3491\" aria-describedby=\"caption-attachment-3491\" style=\"width: 557px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3491\" src=\"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2023\/04\/Carabobo-Futbol-Sala.jpg\" alt=\"carabobo futbol sala femenino\" width=\"557\" height=\"348\" srcset=\"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2023\/04\/Carabobo-Futbol-Sala.jpg 557w, https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2023\/04\/Carabobo-Futbol-Sala-300x187.jpg 300w\" sizes=\"auto, (max-width: 557px) 100vw, 557px\" \/><figcaption id=\"caption-attachment-3491\" class=\"wp-caption-text\">Carabobe\u00f1as en el equipo de Futbol Sala Femenino de Venezuela<\/figcaption><\/figure>\n<p>Felicitaciones especiales a las carabobe\u00f1as B\u00e1rbara L\u00f3pez, Franchesca Palencia, Anyibel Zapata, Karla Padr\u00f3n y Glorimar Su\u00e1rez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El equipo de Venezuela B obtiene el oro luego de vencer 3 goles por 2 al equipo nacional A en la quinta edici\u00f3n de los juegos deportivos que re\u00fane a los pa\u00edses del Alba e invitados especiales. El combinado Sub20, qui\u00e9nes jugaron de color blanco, madrugaron en el marcador a sus similares con gol de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3492,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[3],"tags":[213],"class_list":["post-3488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales","tag-juegos-alba"],"_links":{"self":[{"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/posts\/3488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/comments?post=3488"}],"version-history":[{"count":3,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/posts\/3488\/revisions"}],"predecessor-version":[{"id":3493,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/posts\/3488\/revisions\/3493"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/media\/3492"}],"wp:attachment":[{"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/media?parent=3488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/categories?post=3488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/tags?post=3488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}