{"id":3305,"date":"2023-03-12T12:51:52","date_gmt":"2023-03-12T16:51:52","guid":{"rendered":"https:\/\/fundadeporte.gob.ve\/carabobo\/?p=3305"},"modified":"2023-07-20T09:34:53","modified_gmt":"2023-07-20T13:34:53","slug":"carabobenos-levantamiento-de-pesas","status":"publish","type":"post","link":"https:\/\/fundadeporte.gob.ve\/carabobo\/carabobenos-levantamiento-de-pesas\/","title":{"rendered":"Cinco carabobe\u00f1os ratifican su permanencia en la selecci\u00f3n nacional de Levantamiento de Pesas"},"content":{"rendered":"<h4>Katherine Echandia, Kerlys Montilla, G\u00e9nesis Rodr\u00edguez, Yaniuska Espinosa y Jhohan Sanguino, son las atletas que confirmaron su continuidad en el equipo nacional de Venezuela.<\/h4>\n<figure id=\"attachment_2699\" aria-describedby=\"caption-attachment-2699\" style=\"width: 1045px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2699 size-full\" src=\"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/10\/echandia-Juegos-Suramericanos-Asuncion-a.jpg\" alt=\"\" width=\"1045\" height=\"678\" srcset=\"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/10\/echandia-Juegos-Suramericanos-Asuncion-a.jpg 1045w, https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/10\/echandia-Juegos-Suramericanos-Asuncion-a-300x195.jpg 300w, https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/10\/echandia-Juegos-Suramericanos-Asuncion-a-1024x664.jpg 1024w, https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/10\/echandia-Juegos-Suramericanos-Asuncion-a-768x498.jpg 768w\" sizes=\"auto, (max-width: 1045px) 100vw, 1045px\" \/><figcaption id=\"caption-attachment-2699\" class=\"wp-caption-text\">Katherine Echandia<\/figcaption><\/figure>\n<p>Echandia en la categor\u00eda 44 kilogramos fue campeona de los atletas Juegos Suramericanos de la Juventud del 2017, Campeona de los Juegos Ol\u00edmpicos de la Juventud Buenos Aires 2018, donde adem\u00e1s fue la abanderada de la delegaci\u00f3n Venezolana. En los Juegos Suramericanos Asunci\u00f3n 2022 se dio un ba\u00f1o de oro en la divisi\u00f3n de los 49 kilogramos.<\/p>\n<figure id=\"attachment_1561\" aria-describedby=\"caption-attachment-1561\" style=\"width: 780px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1561\" src=\"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/05\/Kerlys-Montilla.jpg\" alt=\"levantamiento de pesas\" width=\"780\" height=\"470\" srcset=\"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/05\/Kerlys-Montilla.jpg 780w, https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/05\/Kerlys-Montilla-300x181.jpg 300w, https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/05\/Kerlys-Montilla-768x463.jpg 768w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><figcaption id=\"caption-attachment-1561\" class=\"wp-caption-text\">Kerlys Montilla imponiendo una nueva marca<\/figcaption><\/figure>\n<p>Kerlys Montilla, onde\u00f3 la bandera de Venezuela en la inauguraci\u00f3n de los Juegos Suramericanos de la Juventud Rosario 2022 y subi\u00f3 a la cima del podio colg\u00e1ndose la presea dorada en la divisi\u00f3n de los 49 kilogramos.<\/p>\n<p>Mientras que, \u00abla negra\u00bb como cari\u00f1osamente la conocen, G\u00e9nesis Rodr\u00edguez, es Campeona de los Juegos Panamericanos Santo Domingo en la divisi\u00f3n de los 55 kilogramos, medallista de plata en la divisi\u00f3n de los 59 kilos de los Juegos Suramericanos de la Asunci\u00f3n 2022.<\/p>\n<figure id=\"attachment_2707\" aria-describedby=\"caption-attachment-2707\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2707\" src=\"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/10\/Genesis-Rodriguez.jpg\" alt=\"\" width=\"1080\" height=\"699\" srcset=\"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/10\/Genesis-Rodriguez.jpg 1080w, https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/10\/Genesis-Rodriguez-300x194.jpg 300w, https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/10\/Genesis-Rodriguez-1024x663.jpg 1024w, https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/10\/Genesis-Rodriguez-768x497.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><figcaption id=\"caption-attachment-2707\" class=\"wp-caption-text\">G\u00e9nesis Rodr\u00edguez<\/figcaption><\/figure>\n<p>Para la atleta m\u00e1s experimentada de esta disciplina, la oriunda de Puerto Cabello, Yaniuska Espinosa, ha sido Campeona Centroamericana y del Caribe en Mayag\u00fcez 2010, es atleta Ol\u00edmpica de R\u00edo 2016 donde obtuvo diploma ol\u00edmpico tras ubicarse en la 7ma posici\u00f3n de la divisi\u00f3n +75 kilogramos, quinta en el mundial de Polonia, nos ha representado en Juegos Bolivarianos, Panamericanos donde ha subido el podio en varias ocasiones.<\/p>\n<figure id=\"attachment_3307\" aria-describedby=\"caption-attachment-3307\" style=\"width: 697px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3307\" src=\"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2023\/03\/Yaniuska-Espinosa.jpg\" alt=\"Yaniuska Espinosa levantamiento de pesas\" width=\"697\" height=\"560\" srcset=\"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2023\/03\/Yaniuska-Espinosa.jpg 697w, https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2023\/03\/Yaniuska-Espinosa-300x241.jpg 300w\" sizes=\"auto, (max-width: 697px) 100vw, 697px\" \/><figcaption id=\"caption-attachment-3307\" class=\"wp-caption-text\">Yaniuska Espinosa<\/figcaption><\/figure>\n<figure id=\"attachment_2733\" aria-describedby=\"caption-attachment-2733\" style=\"width: 1079px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2733\" src=\"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/10\/Jhohan-Sanguino.jpg\" alt=\"levantamiento de pesas\" width=\"1079\" height=\"796\" srcset=\"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/10\/Jhohan-Sanguino.jpg 1079w, https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/10\/Jhohan-Sanguino-300x221.jpg 300w, https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/10\/Jhohan-Sanguino-1024x755.jpg 1024w, https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/10\/Jhohan-Sanguino-768x567.jpg 768w\" sizes=\"auto, (max-width: 1079px) 100vw, 1079px\" \/><figcaption id=\"caption-attachment-2733\" class=\"wp-caption-text\">Jhohan Sanguino<\/figcaption><\/figure>\n<p>En la rama masculina, har\u00e1 lo propio Jhohan Sanguino quien vuelve a inscribir su nombre en el equipo vinotinto. Sanguino es el actual campe\u00f3n continental de la Asunci\u00f3n 2022 al totalizar 363 kilos para colgarse el metal dorado y adue\u00f1arse de la divisi\u00f3n de los 109 kilos masculino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Katherine Echandia, Kerlys Montilla, G\u00e9nesis Rodr\u00edguez, Yaniuska Espinosa y Jhohan Sanguino, son las atletas que confirmaron su continuidad en el equipo nacional de Venezuela. Echandia en la categor\u00eda 44 kilogramos fue campeona de los atletas Juegos Suramericanos de la Juventud del 2017, Campeona de los Juegos Ol\u00edmpicos de la Juventud Buenos Aires 2018, donde adem\u00e1s [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3308,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[28],"tags":[138,53,54,135],"class_list":["post-3305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atletismo","tag-jhohan-sanguino","tag-katherine-echandia","tag-kerlys-montilla","tag-yaniuska-espinosa"],"_links":{"self":[{"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/posts\/3305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/comments?post=3305"}],"version-history":[{"count":4,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/posts\/3305\/revisions"}],"predecessor-version":[{"id":4031,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/posts\/3305\/revisions\/4031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/media\/3308"}],"wp:attachment":[{"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/media?parent=3305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/categories?post=3305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/tags?post=3305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}