{"id":2701,"date":"2022-10-03T10:55:00","date_gmt":"2022-10-03T14:55:00","guid":{"rendered":"https:\/\/fundadeporte.gob.ve\/carabobo\/?p=2701"},"modified":"2022-10-03T10:55:00","modified_gmt":"2022-10-03T14:55:00","slug":"joselytn-y-edymar-brea-en-la-gatorade-caracas-rock-2022","status":"publish","type":"post","link":"https:\/\/fundadeporte.gob.ve\/carabobo\/joselytn-y-edymar-brea-en-la-gatorade-caracas-rock-2022\/","title":{"rendered":"Las carabobe\u00f1as Joselytn y Edymar Brea se impusieron en la Gatorade Caracas Rock 2022"},"content":{"rendered":"<h4><span style=\"color: #800000;\">Los maratonistas y hermanas alcanzaron las m\u00e1ximas posiciones en la categor\u00eda femenina en la reciente edici\u00f3n del evento deportivo que reuni\u00f3 a m\u00e1s de 8.000 corredores de toda Venezuela.<\/span><\/h4>\n<p>La atleta Joselyn Brea implant\u00f3 un nuevo r\u00e9cord nacional de 10 kil\u00f3metros al registrar 32.34 minutos,\u00a0superando por m\u00e1s de dos minutos su mejor registro de la competencia. Adem\u00e1s, logr\u00f3 bajar por poco m\u00e1s de un minuto su propio r\u00e9cord nacional, manteni\u00e9ndose como la mujer m\u00e1s r\u00e1pida del pa\u00eds.<\/p>\n<p>\u201cEstoy muy contenta, la verdad no me esperaba correr tan r\u00e1pido, vengo de hacer una buena preparaci\u00f3n a base de altura. El objetivo son los Juegos Sudamericanos en 15 d\u00edas, me encuentro en un buen estado de forma y espero luchar por esa medalla\u201d, expres\u00f3.<br \/>\n\u201cNo pens\u00e9 que iba a correr tan r\u00e1pido, simplemente estaba disfrutando la carrera. Es una energ\u00eda incre\u00edble correr aqu\u00ed en Caracas\u201d, concluy\u00f3 Joselyn Brea.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2703\" src=\"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/10\/Gatorade-Caracas-Rock-2022-b.jpg\" alt=\"\" width=\"675\" height=\"400\" srcset=\"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/10\/Gatorade-Caracas-Rock-2022-b.jpg 675w, https:\/\/fundadeporte.gob.ve\/carabobo\/wp-content\/uploads\/2022\/10\/Gatorade-Caracas-Rock-2022-b-300x178.jpg 300w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><\/p>\n<p>El segundo lugar de la categor\u00eda femenina fue para su hermana Edymar Brea logrando 33.41 minutos. El podio lo cerr\u00f3 Raquel Agudelo marcando 35.54 minutos.<\/p>\n<p>En la disciplina Masculina, Marvin Blanco consigui\u00f3 un tiempo de 29.59 minutos, disminuyendo once segundos de su mejor registro y r\u00e9cord de la carrera. El segundo lugar se lo llev\u00f3 Winton Palma (30.04 minutos) y el tercer lugar fue para Jos\u00e9 Daniel Gonz\u00e1lez (30.50 minutos).<\/p>\n<p>La tradicional competencia sali\u00f3 de la\u00a0Autopista de Prados del Este\u00a0a las 7:00 de la ma\u00f1ana y culmin\u00f3 en la Plaza Alfredo Sadel de las Mercedes, cerca de las 9:00 am. Tras la carrera, se presentaron para los asistentes algunos artistas venezolanos, como los recientes ganadores del Latin Grammy, la\u00a0S\u00faper Banda de Venezuela Guaco\u00a0y varias bandas de rock criollas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los maratonistas y hermanas alcanzaron las m\u00e1ximas posiciones en la categor\u00eda femenina en la reciente edici\u00f3n del evento deportivo que reuni\u00f3 a m\u00e1s de 8.000 corredores de toda Venezuela. La atleta Joselyn Brea implant\u00f3 un nuevo r\u00e9cord nacional de 10 kil\u00f3metros al registrar 32.34 minutos,\u00a0superando por m\u00e1s de dos minutos su mejor registro de la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2704,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[28],"tags":[50,49],"class_list":["post-2701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atletismo","tag-edymar-brea","tag-joselyn-brea"],"_links":{"self":[{"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/posts\/2701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/comments?post=2701"}],"version-history":[{"count":2,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/posts\/2701\/revisions"}],"predecessor-version":[{"id":2705,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/posts\/2701\/revisions\/2705"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/media\/2704"}],"wp:attachment":[{"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/media?parent=2701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/categories?post=2701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundadeporte.gob.ve\/carabobo\/wp-json\/wp\/v2\/tags?post=2701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}